{"id":15953,"date":"2025-01-12T23:51:57","date_gmt":"2025-01-13T07:51:57","guid":{"rendered":"https:\/\/shengenfab.com\/?p=15953"},"modified":"2026-05-08T19:44:10","modified_gmt":"2026-05-09T03:44:10","slug":"dry-etching-vs-wet-etching","status":"publish","type":"post","link":"https:\/\/shengenfab.com\/pt\/dry-etching-vs-wet-etching\/","title":{"rendered":"Gravura a seco vs Gravura h\u00famida: Qual \u00e9 a diferen\u00e7a"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"15953\" class=\"elementor elementor-15953\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6354a80a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6354a80a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a27f66e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a27f66e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-122bf684 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"122bf684\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d1e1a0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d1e1a0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b0fc70f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b0fc70f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e57b69d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e57b69d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a31d067 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a31d067\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-545ad4f\" data-id=\"545ad4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9799c2 elementor-widget elementor-widget-text-editor\" data-id=\"e9799c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Os processos de grava\u00e7\u00e3o desempenham um papel crucial no fabrico de semicondutores e na microfabrica\u00e7\u00e3o. Os engenheiros enfrentam frequentemente desafios na sele\u00e7\u00e3o do m\u00e9todo de grava\u00e7\u00e3o adequado para os seus projectos. Compreender as diferen\u00e7as entre a grava\u00e7\u00e3o a seco e a grava\u00e7\u00e3o h\u00famida pode ter um impacto significativo na qualidade do produto e na efici\u00eancia da produ\u00e7\u00e3o.<\/p><p>A escolha da t\u00e9cnica de grava\u00e7\u00e3o correta pode melhorar o seu processo de fabrico. Vamos explorar as especificidades de cada m\u00e9todo, incluindo os seus processos e aplica\u00e7\u00f5es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7b67e3 elementor-widget elementor-widget-image\" data-id=\"f7b67e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"666\" height=\"375\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/Dry-Etching-vs.-Wet-Etching.jpg\" class=\"attachment-large size-large wp-image-15961\" alt=\"Gravura a seco vs. gravura h\u00famida\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/Dry-Etching-vs.-Wet-Etching.jpg 666w, https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/Dry-Etching-vs.-Wet-Etching-300x169.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/Dry-Etching-vs.-Wet-Etching-18x10.jpg 18w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4f5473 elementor-widget elementor-widget-text-editor\" data-id=\"a4f5473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">O que \u00e9 a gravura?<\/h2>\n<p><\/p>\n<p>A grava\u00e7\u00e3o \u00e9 um processo de fabrico que remove seletivamente material de um substrato para criar padr\u00f5es ou desenhos desejados. A remo\u00e7\u00e3o controlada de material cria canais, cavidades e padr\u00f5es com profundidades e geometrias espec\u00edficas.<\/p>\n<p><\/p>\n<p>Tradicionalmente, isto envolve a utiliza\u00e7\u00e3o de \u00e1cidos fortes ou mordentes para cortar as partes n\u00e3o protegidas de uma superf\u00edcie met\u00e1lica. Nas aplica\u00e7\u00f5es modernas, as t\u00e9cnicas de grava\u00e7\u00e3o evolu\u00edram para incluir v\u00e1rios m\u00e9todos qu\u00edmicos e f\u00edsicos adequados a diferentes materiais, incluindo metais, semicondutores e cer\u00e2micas.<\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">M\u00e9todos de gravura: Uma vis\u00e3o geral das duas principais abordagens<\/h3>\n<p><\/p>\n<p>Os m\u00e9todos de grava\u00e7\u00e3o dividem-se em duas categorias principais com base nos seus mecanismos de remo\u00e7\u00e3o de material. A grava\u00e7\u00e3o a seco utiliza gravadores gasosos e plasma, enquanto a grava\u00e7\u00e3o h\u00famida utiliza solu\u00e7\u00f5es qu\u00edmicas l\u00edquidas. Cada abordagem oferece vantagens distintas para diferentes cen\u00e1rios de fabrico.<\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">Factores a considerar na escolha do m\u00e9todo de grava\u00e7\u00e3o<\/h2>\n<p><\/p>\n<p>A sele\u00e7\u00e3o do m\u00e9todo de grava\u00e7\u00e3o correto tem impacto na qualidade e no custo do produto. Eis o que os engenheiros precisam de avaliar:<\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">Seletividade<\/h3>\n<p><\/p>\n<p>A seletividade refere-se ao r\u00e1cio das taxas de corros\u00e3o entre o material a ser gravado e as camadas ou m\u00e1scaras subjacentes. Uma elevada seletividade \u00e9 crucial, uma vez que determina a efic\u00e1cia com que o agente de corros\u00e3o remove apenas o material visado, preservando os restantes.<\/p>\n<p><\/p>\n<p>Por exemplo, uma seletividade de grava\u00e7\u00e3o de 10:1 significa que o material de interesse \u00e9 removido dez vezes mais rapidamente do que o material da m\u00e1scara. Esta carater\u00edstica \u00e9 vital em aplica\u00e7\u00f5es onde \u00e9 necess\u00e1ria uma modela\u00e7\u00e3o precisa, assegurando que apenas \u00e1reas espec\u00edficas s\u00e3o afectadas durante o processo de grava\u00e7\u00e3o.<\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">Taxa de grava\u00e7\u00e3o<\/h3>\n<p><\/p>\n<p>A velocidade de grava\u00e7\u00e3o mede a rapidez com que o material \u00e9 removido durante o processo de grava\u00e7\u00e3o, normalmente expressa em micr\u00f3metros por minuto (\u00b5m\/min). Embora uma taxa de corros\u00e3o mais elevada possa conduzir a tempos de produ\u00e7\u00e3o mais r\u00e1pidos, \u00e9 essencial equilibrar a velocidade com a precis\u00e3o.<\/p>\n<p><\/p>\n<p>A grava\u00e7\u00e3o r\u00e1pida pode comprometer a resolu\u00e7\u00e3o das carater\u00edsticas ou levar a cortes indesejados. Por conseguinte, \u00e9 crucial selecionar um m\u00e9todo de grava\u00e7\u00e3o com uma taxa adequada para a aplica\u00e7\u00e3o espec\u00edfica.<\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">Uniformidade de grava\u00e7\u00e3o<\/h3>\n<p><\/p>\n<p>A uniformidade da grava\u00e7\u00e3o indica a consist\u00eancia com que a taxa de grava\u00e7\u00e3o \u00e9 aplicada em todo o substrato. Uma grava\u00e7\u00e3o n\u00e3o uniforme pode resultar em varia\u00e7\u00f5es nas dimens\u00f5es das carater\u00edsticas e na qualidade geral. A obten\u00e7\u00e3o da uniformidade pode ser influenciada por v\u00e1rios factores, incluindo o design da c\u00e2mara, a distribui\u00e7\u00e3o do fluxo de g\u00e1s na grava\u00e7\u00e3o a seco e a composi\u00e7\u00e3o da solu\u00e7\u00e3o na grava\u00e7\u00e3o a h\u00famido.<\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">Outras considera\u00e7\u00f5es<\/h3>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Gravura isotr\u00f3pica<\/h4>\n<p><\/p>\n<p>A grava\u00e7\u00e3o isotr\u00f3pica ocorre uniformemente em todas as direc\u00e7\u00f5es, resultando em perfis arredondados e potenciais cortes inferiores. Este m\u00e9todo \u00e9 frequentemente mais r\u00e1pido, mas pode n\u00e3o proporcionar a precis\u00e3o necess\u00e1ria para desenhos complexos.\u00a0<\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Gravura anisotr\u00f3pica<\/h4>\n<p><\/p>\n<p>A grava\u00e7\u00e3o anisotr\u00f3pica remove preferencialmente o material em direc\u00e7\u00f5es espec\u00edficas, permitindo obter carater\u00edsticas mais n\u00edtidas e arestas bem definidas. Este m\u00e9todo \u00e9 ideal para aplica\u00e7\u00f5es de alta precis\u00e3o, como o fabrico de semicondutores e o fabrico de MEMS.\u00a0<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbab724 elementor-widget elementor-widget-image\" data-id=\"cbab724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"419\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/wet-etch-vs-dry-etch.jpg\" class=\"attachment-large size-large wp-image-15962\" alt=\"grava\u00e7\u00e3o a h\u00famido vs grava\u00e7\u00e3o a seco\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/wet-etch-vs-dry-etch.jpg 1024w, https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/wet-etch-vs-dry-etch-300x157.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/wet-etch-vs-dry-etch-768x402.jpg 768w, https:\/\/shengenfab.com\/wp-content\/uploads\/2025\/01\/wet-etch-vs-dry-etch-18x9.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77207d4 elementor-widget elementor-widget-text-editor\" data-id=\"77207d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><h2 class=\"wp-block-heading\">Gravura a seco: no\u00e7\u00f5es b\u00e1sicas<\/h2><p> <\/p><p>A grava\u00e7\u00e3o a seco representa uma pedra angular do fabrico moderno de microeletr\u00f3nica. Vamos analisar os seus principais aspectos:<\/p><p> <\/p><h3 class=\"wp-block-heading\">Defini\u00e7\u00e3o e vis\u00e3o geral da gravura a seco<\/h3><p> <\/p><p>A grava\u00e7\u00e3o a seco \u00e9 um processo de remo\u00e7\u00e3o de material que utiliza gases ionizados, ou plasma, para gravar padr\u00f5es num substrato. Ao contr\u00e1rio da grava\u00e7\u00e3o a h\u00famido, que depende de qu\u00edmicos l\u00edquidos, a grava\u00e7\u00e3o a seco oferece maior precis\u00e3o e controlo, tornando-a ideal para aplica\u00e7\u00f5es de fabrico de semicondutores e microfabrica\u00e7\u00e3o.<\/p><p> <\/p><p>Esta t\u00e9cnica cria carater\u00edsticas intrincadas com um m\u00ednimo de rebaixamento, resultando em r\u00e1cios de aspeto elevados e geometrias bem definidas.<\/p><p> <\/p><h3 class=\"wp-block-heading\">Processo de gravura a seco<\/h3><p> <\/p><p>O processo de grava\u00e7\u00e3o a seco envolve v\u00e1rias etapas fundamentais:<\/p><p> <\/p><ol class=\"wp-block-list\"><li><strong>Prepara\u00e7\u00e3o<\/strong>: Um substrato, normalmente uma pastilha de semicondutor, \u00e9 colocado numa c\u00e2mara de v\u00e1cuo.<\/li> <li><strong>Gera\u00e7\u00e3o de plasma<\/strong>: Os gases reactivos s\u00e3o introduzidos na c\u00e2mara e ionizados com energia de radiofrequ\u00eancia (RF), criando um plasma de electr\u00f5es livres e i\u00f5es de carga positiva.<\/li> <li><strong>Remo\u00e7\u00e3o de Materiais<\/strong>: Os i\u00f5es do plasma s\u00e3o acelerados em dire\u00e7\u00e3o ao substrato, onde reagem quimicamente com o material da superf\u00edcie ou deslocam fisicamente os \u00e1tomos. O resultado \u00e9 a remo\u00e7\u00e3o selectiva do material, camada por camada.<\/li> <li><strong>Escape<\/strong>: Os subprodutos da rea\u00e7\u00e3o s\u00e3o evacuados da c\u00e2mara, permitindo um processamento cont\u00ednuo.<\/li><\/ol><p> <\/p><h3 class=\"wp-block-heading\">Tipos de t\u00e9cnicas de gravura a seco<\/h3><p> <\/p><h4 class=\"wp-block-heading\">Grava\u00e7\u00e3o por plasma<\/h4><p> <\/p><p>A grava\u00e7\u00e3o por plasma \u00e9 uma t\u00e9cnica de grava\u00e7\u00e3o a seco amplamente utilizada que emprega plasma para remover material do substrato. Dependendo dos par\u00e2metros do processo, \u00e9 poss\u00edvel obter perfis de grava\u00e7\u00e3o isotr\u00f3picos e anisotr\u00f3picos.<\/p><p> <\/p><h4 class=\"wp-block-heading\">Gravura i\u00f3nica reactiva (RIE)<\/h4><p> <\/p><p>A gravura i\u00f3nica reactiva (RIE) combina processos de gravura qu\u00edmica e f\u00edsica. Na RIE, os i\u00f5es reactivos gerados no plasma reagem quimicamente com o substrato, proporcionando simultaneamente um controlo direcional atrav\u00e9s do bombardeamento f\u00edsico.<\/p><p> <\/p><h4 class=\"wp-block-heading\">Grava\u00e7\u00e3o por feixe de i\u00f5es (IBE)<\/h4><p> <\/p><p>A grava\u00e7\u00e3o por feixe de i\u00f5es (IBE) utiliza um feixe focalizado de i\u00f5es dirigido \u00e0 superf\u00edcie do substrato. Esta t\u00e9cnica proporciona uma grava\u00e7\u00e3o altamente direcional e \u00e9 essencialmente f\u00edsica, permitindo um controlo preciso da remo\u00e7\u00e3o do material.<\/p><p> <\/p><h3 class=\"wp-block-heading\">Vantagens e desvantagens da grava\u00e7\u00e3o a seco<\/h3><p> <\/p><p><strong>Vantagens:<\/strong><\/p><p> <\/p><ul class=\"wp-block-list\"><li><strong>Precis\u00e3o<\/strong>: As t\u00e9cnicas de grava\u00e7\u00e3o a seco permitem obter carater\u00edsticas finas com r\u00e1cios de aspeto elevados.<\/li> <li><strong>Controlo<\/strong>: Oferece um melhor controlo sobre o perfil de grava\u00e7\u00e3o do que a grava\u00e7\u00e3o h\u00famida, permitindo uma grava\u00e7\u00e3o anisotr\u00f3pica.<\/li> <li><strong>Redu\u00e7\u00e3o da utiliza\u00e7\u00e3o de produtos qu\u00edmicos<\/strong>: Normalmente, requer menos produtos qu\u00edmicos do que os processos h\u00famidos, o que facilita a elimina\u00e7\u00e3o dos subprodutos.<\/li> <li><strong>Automa\u00e7\u00e3o<\/strong>: Pode ser automatizado para aumentar a seguran\u00e7a e a efici\u00eancia durante o funcionamento.<\/li><\/ul><p> <\/p><p><strong>Desvantagens:<\/strong><\/p><p> <\/p><ul class=\"wp-block-list\"><li><strong>Custo<\/strong>: O equipamento necess\u00e1rio para a grava\u00e7\u00e3o a seco tende a ser mais caro do que o da grava\u00e7\u00e3o a h\u00famido.<\/li> <li><strong>Complexidade<\/strong>: Requer conhecimentos especializados e experi\u00eancia para funcionar eficazmente.<\/li> <li><strong>Danos potenciais<\/strong>: Os i\u00f5es de alta energia podem causar danos ou defeitos na superf\u00edcie se n\u00e3o forem cuidadosamente controlados.<\/li><\/ul><p> <\/p><h2 class=\"wp-block-heading\">Gravura h\u00famida: no\u00e7\u00f5es b\u00e1sicas<\/h2><p> <\/p><p>A grava\u00e7\u00e3o por via h\u00famida continua a ser um m\u00e9todo amplamente adotado no fabrico. Eis uma an\u00e1lise pormenorizada:<\/p><p> <\/p><h3 class=\"wp-block-heading\">Defini\u00e7\u00e3o e vis\u00e3o geral da grava\u00e7\u00e3o a h\u00famido<\/h3><p> <\/p><p>A grava\u00e7\u00e3o por via h\u00famida \u00e9 um processo qu\u00edmico que remove seletivamente material de um substrato utilizando l\u00edquidos de grava\u00e7\u00e3o. Estes gravadores s\u00e3o normalmente compostos por solu\u00e7\u00f5es \u00e1cidas ou b\u00e1sicas que reagem com o material do substrato, formando produtos sol\u00faveis que podem ser lavados.<\/p><p> <\/p><p>Este m\u00e9todo \u00e9 amplamente utilizado na microfabrica\u00e7\u00e3o e no fabrico de semicondutores devido \u00e0 sua simplicidade e efic\u00e1cia na cria\u00e7\u00e3o de padr\u00f5es complexos em v\u00e1rios materiais.<\/p><p> <\/p><h3 class=\"wp-block-heading\">Processo de gravura h\u00famida<\/h3><p> <\/p><p>O processo de grava\u00e7\u00e3o a h\u00famido envolve geralmente as seguintes etapas:<\/p><p> <\/p><ol class=\"wp-block-list\"><li><strong>Prepara\u00e7\u00e3o<\/strong>: Um substrato, frequentemente revestido com uma camada protetora (m\u00e1scara), \u00e9 imerso ou pulverizado com uma solu\u00e7\u00e3o de corros\u00e3o.<\/li> <li><strong>Rea\u00e7\u00e3o qu\u00edmica<\/strong>: O agente de corros\u00e3o reage com as \u00e1reas expostas do substrato, dissolvendo o material. A cin\u00e9tica da rea\u00e7\u00e3o depende de factores como a temperatura, a concentra\u00e7\u00e3o e a natureza do agente de corros\u00e3o.<\/li> <li><strong>Remo\u00e7\u00e3o de subprodutos<\/strong>: Os produtos sol\u00faveis formados durante a rea\u00e7\u00e3o s\u00e3o lavados, deixando o padr\u00e3o desejado no substrato.<\/li> <li><strong>Lavagem<\/strong>: Ap\u00f3s o condicionamento, o substrato \u00e9 lavado para remover qualquer res\u00edduo de condicionador e subprodutos.<\/li><\/ol><p> <\/p><h3 class=\"wp-block-heading\">Tipos de solu\u00e7\u00f5es de gravura h\u00famida<\/h3><p> <\/p><p>As solu\u00e7\u00f5es de corros\u00e3o h\u00famida podem ser classificadas com base na sua natureza qu\u00edmica:<\/p><p> <\/p><h4 class=\"wp-block-heading\">Solu\u00e7\u00f5es \u00e1cidas<\/h4><p> <\/p><p>As solu\u00e7\u00f5es \u00e1cidas s\u00e3o normalmente utilizadas nos processos de grava\u00e7\u00e3o a h\u00famido. Os exemplos incluem:<\/p><p> <\/p><ul class=\"wp-block-list\"><li><strong>\u00c1cido clor\u00eddrico (HCl)<\/strong>: Frequentemente utilizado para metais e alguns \u00f3xidos.<\/li> <li><strong>\u00c1cido fluor\u00eddrico (HF)<\/strong>: Eficaz para gravar di\u00f3xido de sil\u00edcio e materiais de vidro.<\/li> <li><strong>\u00c1cido n\u00edtrico (HNO3)<\/strong>: Utilizado para metais como o alum\u00ednio e para fins de limpeza.<\/li><\/ul><p> <\/p><p>Estes \u00e1cidos reagem agressivamente com v\u00e1rios materiais, o que os torna adequados para aplica\u00e7\u00f5es de grava\u00e7\u00e3o selectiva.<\/p><p> <\/p><h4 class=\"wp-block-heading\">Solu\u00e7\u00f5es b\u00e1sicas<\/h4><p> <\/p><p>As solu\u00e7\u00f5es b\u00e1sicas tamb\u00e9m desempenham um papel importante na grava\u00e7\u00e3o h\u00famida. Os exemplos incluem:<\/p><p> <\/p><ul class=\"wp-block-list\"><li><strong>Hidr\u00f3xido de s\u00f3dio (NaOH)<\/strong>: Utilizado habitualmente para gravar o sil\u00edcio e certos metais.<\/li> <li><strong>Hidr\u00f3xido de pot\u00e1ssio (KOH)<\/strong>: Frequentemente utilizado no processamento de semicondutores devido \u00e0 sua efic\u00e1cia no sil\u00edcio.<\/li><\/ul><p> <\/p><p>As solu\u00e7\u00f5es b\u00e1sicas tendem a ser menos agressivas do que as \u00e1cidas, mas, dependendo da aplica\u00e7\u00e3o, podem ainda assim remover eficazmente o material.<\/p><p> <\/p><h3 class=\"wp-block-heading\">Vantagens e desvantagens da grava\u00e7\u00e3o a h\u00famido<\/h3><p> <\/p><p><strong>Vantagens:<\/strong><\/p><p> <\/p><ul class=\"wp-block-list\"><li><strong>Simplicidade<\/strong>: Os equipamentos de grava\u00e7\u00e3o por via h\u00famida s\u00e3o geralmente menos complexos e mais econ\u00f3micos do que os sistemas de grava\u00e7\u00e3o por via seca.<\/li> <li><strong>Altas taxas de corros\u00e3o<\/strong>: A grava\u00e7\u00e3o por via h\u00famida oferece normalmente taxas de remo\u00e7\u00e3o de material mais r\u00e1pidas devido ao contacto direto dos l\u00edquidos de grava\u00e7\u00e3o com o substrato.<\/li> <li><strong>Uniformidade<\/strong>: Este m\u00e9todo permite uma grava\u00e7\u00e3o uniforme em grandes \u00e1reas, o que \u00e9 ben\u00e9fico para o processamento em lote.<\/li><\/ul><p> <\/p><p><strong>Desvantagens:<\/strong><\/p><p> <\/p><ul class=\"wp-block-list\"><li><strong>Natureza isotr\u00f3pica<\/strong>: A grava\u00e7\u00e3o por via h\u00famida \u00e9 frequentemente isotr\u00f3pica, o que significa que remove o material uniformemente em todas as direc\u00e7\u00f5es, o que pode levar a cortes por baixo das m\u00e1scaras de prote\u00e7\u00e3o.<\/li> <li><strong>Manuseamento de produtos qu\u00edmicos<\/strong>: Requer um manuseamento cuidadoso dos produtos qu\u00edmicos perigosos e a elimina\u00e7\u00e3o adequada dos res\u00edduos.<\/li> <li><strong>Precis\u00e3o Limitada<\/strong>: A obten\u00e7\u00e3o de carater\u00edsticas finas abaixo de 1 micr\u00f3metro pode ser um desafio devido ao efeito de corros\u00e3o lateral.<\/li><\/ul><p> <\/p><h2 class=\"wp-block-heading\">Qual \u00e9 a diferen\u00e7a entre a grava\u00e7\u00e3o a seco e a grava\u00e7\u00e3o h\u00famida?<\/h2><p> <\/p><p>A grava\u00e7\u00e3o a seco e a grava\u00e7\u00e3o h\u00famida s\u00e3o duas t\u00e9cnicas fundamentais utilizadas na microfabrica\u00e7\u00e3o e no fabrico de semicondutores. Cada uma tem carater\u00edsticas distintas que a tornam adequada para diferentes aplica\u00e7\u00f5es. Segue-se uma compara\u00e7\u00e3o r\u00e1pida das duas t\u00e9cnicas de grava\u00e7\u00e3o para compreender rapidamente as diferen\u00e7as.<\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d0e570 uael-header-sticky-no uael-border-yes elementor-widget elementor-widget-uael-table\" data-id=\"4d0e570\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div itemscope class=\"uael-table-wrapper\" itemtype=\"http:\/\/schema.org\/Table\">\n\t\t\t<table id=\"uael-table-id-4d0e570\" class=\"uael-text-break uael-column-rules uael-table\" data-sort-table=\"no\" data-show-entry=\"no\" data-searchable=\"no\" data-responsive=\"no\">\n\t\t\t<thead>\n\t\t\t\t\t\t\t\t\t<tr class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"0\" class=\"sort-this elementor-repeater-item-0 uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Recurso<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"1\" class=\"sort-this elementor-repeater-item-1 uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Gravura a seco<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<th data-sort=\"2\" class=\"sort-this elementor-repeater-item-2 uael-table-col uael-table-head-cell-text\" scope=\"col\">\n\t\t\t\t\t\t\t\t<span class=\"sort-style\">\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Gravura h\u00famida<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t<\/thead>\n\t\t\t<tbody>\n\t\t\t\t<!-- ROWS -->\n\t\t\t\t\t\t\t\t<tr data-entry=\"1\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0\" data-title=\"\ufeffFeature\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Tipo de processo<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1\" data-title=\"Dry Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Utiliza gases ou plasmas para a remo\u00e7\u00e3o de material<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2\" data-title=\"Wet Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Utiliza produtos qu\u00edmicos l\u00edquidos (gravadores)<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr data-entry=\"2\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0\" data-title=\"\ufeffFeature\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Precis\u00e3o<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1\" data-title=\"Dry Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Altamente preciso, pode conseguir uma grava\u00e7\u00e3o anisotr\u00f3pica<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2\" data-title=\"Wet Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Geralmente menos precisos, frequentemente isotr\u00f3picos<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr data-entry=\"3\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0\" data-title=\"\ufeffFeature\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Complexidade do equipamento<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1\" data-title=\"Dry Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Necessidade de equipamento mais complexo e dispendioso<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2\" data-title=\"Wet Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Equipamento mais simples e mais econ\u00f3mico<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr data-entry=\"4\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0\" data-title=\"\ufeffFeature\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Uso Qu\u00edmico<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1\" data-title=\"Dry Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Normalmente, utiliza menos produtos qu\u00edmicos<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2\" data-title=\"Wet Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Requer grandes volumes de produtos qu\u00edmicos<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr data-entry=\"5\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0\" data-title=\"\ufeffFeature\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Taxa de corros\u00e3o<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1\" data-title=\"Dry Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Pode variar; frequentemente mais lento do que a grava\u00e7\u00e3o a h\u00famido<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2\" data-title=\"Wet Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Taxas de corros\u00e3o geralmente mais elevadas<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr data-entry=\"6\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0\" data-title=\"\ufeffFeature\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Seletividade<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1\" data-title=\"Dry Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Menor seletividade em compara\u00e7\u00e3o com o condicionamento h\u00famido<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2\" data-title=\"Wet Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Maior seletividade entre materiais<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr data-entry=\"7\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0\" data-title=\"\ufeffFeature\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Controlo da grava\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1\" data-title=\"Dry Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Maior controlo sobre o perfil de grava\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2\" data-title=\"Wet Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Menos controlo, conduzindo a uma potencial subcota\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr data-entry=\"8\" class=\"uael-table-row\">\n\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0 uael-table-col uael-table-body-cell-text elementor-repeater-item-0\" data-title=\"\ufeffFeature\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Seguran\u00e7a<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1 uael-table-col uael-table-body-cell-text elementor-repeater-item-1\" data-title=\"Dry Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Geralmente mais seguro devido ao menor manuseamento de produtos qu\u00edmicos<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2 uael-table-col uael-table-body-cell-text elementor-repeater-item-2\" data-title=\"Wet Etching\">\n\t\t\t\t\t\t\t<span class=\"uael-table__text\">\n\n\t\t\t\t\t\t\t\t<span class=\"uael-table__text-inner\">Riscos de seguran\u00e7a mais elevados devido a produtos qu\u00edmicos perigosos<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t<\/tbody>\n\t\t<\/table>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d63b764 elementor-widget elementor-widget-text-editor\" data-id=\"d63b764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><h2 class=\"wp-block-heading\">Aplica\u00e7\u00f5es da gravura a seco<\/h2><p> <\/p><p>A grava\u00e7\u00e3o a seco domina o fabrico moderno de microeletr\u00f3nica. \u00c9 aqui que ela se revela inestim\u00e1vel:<\/p><p> <\/p><h3 class=\"wp-block-heading\">Gravura a seco no fabrico de semicondutores<\/h3><p> <\/p><p>O fabrico de semicondutores depende da grava\u00e7\u00e3o a seco pela sua precis\u00e3o e controlo:<\/p><p> <\/p><ul class=\"wp-block-list\"><li>Cria portas de trans\u00edstor \u00e0 nanoescala com paredes laterais verticais<\/li> <li>Forma orif\u00edcios de contacto profundos e estreitos para interliga\u00e7\u00f5es de chips<\/li> <li>Corta trincheiras de isolamento entre componentes activos<\/li> <li>Padr\u00f5es de m\u00faltiplas camadas met\u00e1licas para circuitos complexos<\/li><\/ul><p> <\/p><h3 class=\"wp-block-heading\">O papel da grava\u00e7\u00e3o a seco nos dispositivos MEMS<\/h3><p> <\/p><p>O fabrico de MEMS requer estruturas 3D sofisticadas:<\/p><p> <\/p><ul class=\"wp-block-list\"><li>Corta cavidades precisas para aceler\u00f3metros em sil\u00edcio<\/li> <li>Forma molas e feixes mec\u00e2nicos para sensores<\/li> <li>Cria c\u00e2maras ac\u00fasticas para microfones MEMS<\/li> <li>Remo\u00e7\u00e3o de camadas de sacrif\u00edcio para pe\u00e7as m\u00f3veis<\/li><\/ul><p> <\/p><h3 class=\"wp-block-heading\">Utiliza\u00e7\u00e3o de gravura a seco na produ\u00e7\u00e3o de fotom\u00e1scaras<\/h3><p> <\/p><p>A qualidade da fotom\u00e1scara tem um impacto direto na produ\u00e7\u00e3o de chips:<\/p><p> <\/p><ul class=\"wp-block-list\"><li>Grava padr\u00f5es de cromo com precis\u00e3o nanom\u00e9trica<\/li> <li>Cria elementos de mudan\u00e7a de fase para uma resolu\u00e7\u00e3o melhorada<\/li> <li>Permite repara\u00e7\u00f5es direcionadas de defeitos da m\u00e1scara<\/li> <li>Remove os revestimentos reflectores indesejados<\/li><\/ul><p> <\/p><h3 class=\"wp-block-heading\">Gravura a seco para dispositivos microflu\u00eddicos<\/h3><p> <\/p><p>O fabrico de pastilhas microflu\u00eddicas beneficia do controlo da grava\u00e7\u00e3o a seco:<\/p><p> <\/p><ul class=\"wp-block-list\"><li>Produz profundidades de canal uniformes<\/li> <li>Cria portas de entrada\/sa\u00edda limpas<\/li> <li>Modifica a qu\u00edmica da superf\u00edcie para controlo de fluidos<\/li> <li>Permite dispositivos h\u00edbridos electr\u00f3nicos-flu\u00eddicos<\/li><\/ul><p> <\/p><h2 class=\"wp-block-heading\">Aplica\u00e7\u00f5es da gravura h\u00famida<\/h2><p> <\/p><p>A grava\u00e7\u00e3o a h\u00famido permite uma remo\u00e7\u00e3o econ\u00f3mica de material a granel. Eis como os fabricantes a utilizam:<\/p><p> <\/p><h3 class=\"wp-block-heading\">Gravura h\u00famida no processamento de bolachas de sil\u00edcio<\/h3><p> <\/p><p>A produ\u00e7\u00e3o de bolachas de sil\u00edcio baseia-se na grava\u00e7\u00e3o h\u00famida para:<\/p><p> <\/p><ul class=\"wp-block-list\"><li>Remo\u00e7\u00e3o dos danos da serra ap\u00f3s o corte da bolacha<\/li> <li>Cria\u00e7\u00e3o de marcas de alinhamento da bolacha<\/li> <li>Desbaste de bolachas at\u00e9 \u00e0 espessura final<\/li> <li>Superf\u00edcies texturizadas para uma melhor absor\u00e7\u00e3o da luz<\/li><\/ul><p> <\/p><h3 class=\"wp-block-heading\">Gravura h\u00famida no fabrico de c\u00e9lulas solares<\/h3><p> <\/p><p>Os fabricantes de energia solar utilizam a grava\u00e7\u00e3o h\u00famida para aumentar a efici\u00eancia:<\/p><p> <\/p><ul class=\"wp-block-list\"><li>Texturas de superf\u00edcies de silicone para captar mais luz<\/li> <li>Remove as camadas danificadas dos processos de corte<\/li> <li>Cria estruturas de emissores selectivos<\/li> <li>Limpa os contactos met\u00e1licos antes do revestimento<\/li><\/ul><p> <\/p><h3 class=\"wp-block-heading\">Gravura h\u00famida para deposi\u00e7\u00e3o de pel\u00edcula fina<\/h3><p> <\/p><p>O processamento de pel\u00edcula fina utiliza a grava\u00e7\u00e3o h\u00famida para:<\/p><p> <\/p><ul class=\"wp-block-list\"><li>Camadas de contacto de metal padr\u00e3o<\/li> <li>Remover \u00e1reas de pel\u00edcula indesejadas<\/li> <li>Criar rebordos escalonados para aderir \u00e0 camada<\/li> <li>Definir regi\u00f5es activas do dispositivo<\/li><\/ul><p> <\/p><h3 class=\"wp-block-heading\">Gravura h\u00famida para limpeza e prepara\u00e7\u00e3o de superf\u00edcies<\/h3><p> <\/p><p>A prepara\u00e7\u00e3o da superf\u00edcie exige uma limpeza completa:<\/p><p> <\/p><ul class=\"wp-block-list\"><li>Elimina os contaminantes org\u00e2nicos<\/li> <li>Tiras de \u00f3xidos nativos<\/li> <li>Prepara as superf\u00edcies para <a href=\"https:\/\/shengenfab.com\/pt\/powder-coat-aluminum\/\" target=\"_blank\" rel=\"noreferrer noopener\">Revestimento<\/a><\/li> <li>Ativa as superf\u00edcies para a colagem<\/li><\/ul><p> <\/p><h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2><p> <\/p><p>A grava\u00e7\u00e3o \u00e9 um processo cr\u00edtico no fabrico moderno, com a grava\u00e7\u00e3o a seco e a h\u00famido a desempenharem pap\u00e9is distintos em v\u00e1rias aplica\u00e7\u00f5es. Compreender as diferen\u00e7as entre estes m\u00e9todos permite aos engenheiros e fabricantes selecionar a t\u00e9cnica mais adequada \u00e0s suas necessidades espec\u00edficas.<\/p><p> <\/p><p>N\u00e3o hesite em contactar-nos se pretender melhorar os seus processos de fabrico ou se necessitar de orienta\u00e7\u00e3o especializada sobre t\u00e9cnicas de grava\u00e7\u00e3o. <a href=\"https:\/\/shengenfab.com\/pt\/contact\/\" target=\"_blank\" rel=\"noreferrer noopener\">Contate-nos<\/a> hoje para discutir como podemos apoiar os seus projectos e ajud\u00e1-lo a atingir os seus objectivos!<\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-69adeee8\" data-id=\"69adeee8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a52d1b6 elementor-widget elementor-widget-heading\" data-id=\"3a52d1b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ol\u00e1, chamo-me Kevin Lee<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27f5f956 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"27f5f956\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"640\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/12\/Kevin-Lee.webp\" class=\"attachment-large size-large wp-image-6422\" alt=\"Kevin Lee\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/12\/Kevin-Lee.webp 1024w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/12\/Kevin-Lee-300x240.webp 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/12\/Kevin-Lee-768x614.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16ef8780 elementor-widget elementor-widget-text-editor\" data-id=\"16ef8780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Nos \u00faltimos 10 anos, estive imerso em v\u00e1rias formas de fabrica\u00e7\u00e3o de chapas met\u00e1licas, compartilhando aqui insights interessantes de minhas experi\u00eancias em diversos workshops.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b603b3f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b603b3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shengenfab.com\/pt\/about-author\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SOBRE MIM<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f072de1 elementor-widget elementor-widget-heading\" data-id=\"5f072de1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Entrar em contacto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54b4d793 elementor-button-align-stretch elementor-widget elementor-widget-global elementor-global-893 elementor-widget-form\" data-id=\"54b4d793\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;\\u4e0b\\u4e00\\u4e2a&quot;,&quot;step_previous_label&quot;:&quot;\\u4e0a\\u4e00\\u4e2a&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:76,&quot;sticky_effects_offset&quot;:75,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"\u65b0\u8868\u5355\" aria-label=\"\u65b0\u8868\u5355\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"15953\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"54b4d793\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCorreio eletr\u00f3nico\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Correio eletr\u00f3nico\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_59b0978 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_59b0978\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_59b0978]\" id=\"form-field-field_59b0978\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefone\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Somente n\u00fameros e caracteres de telefone (#, -, *, etc) s\u00e3o aceitos.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMensagem\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensagem\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-upload elementor-field-group elementor-column elementor-field-group-field_3054d6d elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3054d6d\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCarregar ficheiros\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input type=\"file\" name=\"form_fields[field_3054d6d]\" id=\"form-field-field_3054d6d\" class=\"elementor-field elementor-size-sm  elementor-upload-field\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_7cab1df elementor-col-100 recaptcha_v3-inline\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_7cab1df\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6Ld96zomAAAAAFa92bnUaWtgdyyax_AThlz6udzh\" data-type=\"v3\" data-action=\"Form\" data-badge=\"inline\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obter um or\u00e7amento imediato<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f4ab49f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f4ab49f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fe7af79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fe7af79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ed06a88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ed06a88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53149adc custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53149adc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2b6b210b\" data-id=\"2b6b210b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-728e02a6\" data-id=\"728e02a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-436de326 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"436de326\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20530a5\" data-id=\"20530a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fe0faf8 elementor-widget elementor-widget-image\" data-id=\"5fe0faf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"640\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/12\/Kevin-Lee.webp\" class=\"attachment-large size-large wp-image-6422\" alt=\"Kevin Lee\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/12\/Kevin-Lee.webp 1024w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/12\/Kevin-Lee-300x240.webp 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/12\/Kevin-Lee-768x614.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3c77ec92\" data-id=\"3c77ec92\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-276511d elementor-widget elementor-widget-heading\" data-id=\"276511d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kevin Lee<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6653a9b0 elementor-widget elementor-widget-text-editor\" data-id=\"6653a9b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tenho mais de dez anos de experi\u00eancia profissional no fabrico de chapas met\u00e1licas, especializando-me em corte a laser, dobragem, soldadura e t\u00e9cnicas de tratamento de superf\u00edcies. Como Diretor T\u00e9cnico da Shengen, estou empenhado em resolver desafios complexos de fabrico e em promover a inova\u00e7\u00e3o e a qualidade em cada projeto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-20fbd644\" data-id=\"20fbd644\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20d904 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20d904\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f1ae154\" data-id=\"3f1ae154\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6566cd2d elementor-widget elementor-widget-heading\" data-id=\"6566cd2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recursos relacionados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-297b5549 uael-post__link-complete-yes uael-equal__height-yes elementor-widget elementor-widget-uael-posts\" data-id=\"297b5549\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_slides_to_show&quot;:4,&quot;classic_slides_to_show_tablet&quot;:2,&quot;classic_slides_to_show_mobile&quot;:1,&quot;classic_pagination_type&quot;:&quot;ajax&quot;,&quot;classic_show_filters&quot;:&quot;no&quot;}\" data-widget_type=\"uael-posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-post__header\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__body\">\n\t\t\t\n\t\t\n\t\t<div class=\"uael-blog-terms-position- uael-post-image-top uael-post-grid uael-posts\" data-query-type=\"custom\" data-structure=\"normal\" data-layout=\"\" data-page=\"15953\" data-skin=\"classic\" data-filter-default=\"\" data-offset-top=\"30\" >\n\n\t\t\t\t\t\t\t<div class=\"uael-post-grid__inner uael-post__columns-4 uael-post__columns-tablet-2 uael-post__columns-mobile-1\">\n\t\t\t\n<div class=\"uael-post-wrapper   blog\">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/fillet-machining\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Caixa Completa\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/fillet-machining\/\" target=\"_blank\" title=\"Maquina\u00e7\u00e3o de filetes: O que determina o custo e a qualidade da pe\u00e7a\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"419\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/04\/Why-Tight-Internal-Fillets-Get-Expensive.jpg\" class=\"attachment-full size-full wp-image-24569\" alt=\"Porque \u00e9 que os filetes internos apertados ficam caros\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/04\/Why-Tight-Internal-Fillets-Get-Expensive.jpg 750w, https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/04\/Why-Tight-Internal-Fillets-Get-Expensive-300x168.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/04\/Why-Tight-Internal-Fillets-Get-Expensive-18x10.jpg 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/fillet-machining\/\" target=\"_blank\">\n\t\t\t\tMaquina\u00e7\u00e3o de filetes: O que determina o custo e a qualidade da pe\u00e7a\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n\t\t\t13 de abril de 2026\t\t<\/span>\n\t\t\t\t<span class=\"uael-post__comments\">\n\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-comments\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 192c0-88.4-93.1-160-208-160S0 103.6 0 192c0 34.3 14.1 65.9 38 92-13.4 30.2-35.5 54.2-35.8 54.5-2.2 2.3-2.8 5.7-1.5 8.7S4.8 352 8 352c36.6 0 66.9-12.3 88.7-25 32.2 15.7 70.3 25 111.3 25 114.9 0 208-71.6 208-160zm122 220c23.9-26 38-57.7 38-92 0-66.9-53.5-124.2-129.3-148.1.9 6.6 1.3 13.3 1.3 20.1 0 105.9-107.7 192-240 192-10.8 0-21.3-.8-31.7-1.9C207.8 439.6 281.8 480 368 480c41 0 79.1-9.2 111.3-25 21.8 12.7 52.1 25 88.7 25 3.2 0 6.1-1.9 7.3-4.8 1.3-2.9.7-6.3-1.5-8.7-.3-.3-22.4-24.2-35.8-54.5z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/shengenfab.com\/pt\/fillet-machining\/\" target=\"_blank\" aria-labelledby=\"uael-post-24568\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=\"uael-post-24568\">Ler mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   blog\">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/fingerprint-resistant-stainless-steel\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Caixa Completa\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/fingerprint-resistant-stainless-steel\/\" target=\"_blank\" title=\"A\u00e7o inoxid\u00e1vel resistente a impress\u00f5es digitais: como funciona e como escolher\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"409\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/03\/Why-Surface-Appearance-Changes-Product-Perception-1.jpg\" class=\"attachment-full size-full wp-image-24454\" alt=\"Porque \u00e9 que o aspeto da superf\u00edcie altera a perce\u00e7\u00e3o do produto\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/03\/Why-Surface-Appearance-Changes-Product-Perception-1.jpg 750w, https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/03\/Why-Surface-Appearance-Changes-Product-Perception-1-300x164.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/03\/Why-Surface-Appearance-Changes-Product-Perception-1-18x10.jpg 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/fingerprint-resistant-stainless-steel\/\" target=\"_blank\">\n\t\t\t\tA\u00e7o inoxid\u00e1vel resistente a impress\u00f5es digitais: como funciona e como escolher\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n\t\t\t12 de mar\u00e7o de 2026\t\t<\/span>\n\t\t\t\t<span class=\"uael-post__comments\">\n\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-comments\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 192c0-88.4-93.1-160-208-160S0 103.6 0 192c0 34.3 14.1 65.9 38 92-13.4 30.2-35.5 54.2-35.8 54.5-2.2 2.3-2.8 5.7-1.5 8.7S4.8 352 8 352c36.6 0 66.9-12.3 88.7-25 32.2 15.7 70.3 25 111.3 25 114.9 0 208-71.6 208-160zm122 220c23.9-26 38-57.7 38-92 0-66.9-53.5-124.2-129.3-148.1.9 6.6 1.3 13.3 1.3 20.1 0 105.9-107.7 192-240 192-10.8 0-21.3-.8-31.7-1.9C207.8 439.6 281.8 480 368 480c41 0 79.1-9.2 111.3-25 21.8 12.7 52.1 25 88.7 25 3.2 0 6.1-1.9 7.3-4.8 1.3-2.9.7-6.3-1.5-8.7-.3-.3-22.4-24.2-35.8-54.5z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/shengenfab.com\/pt\/fingerprint-resistant-stainless-steel\/\" target=\"_blank\" aria-labelledby=\"uael-post-24442\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=\"uael-post-24442\">Ler mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   blog\">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/oem-vs-contract-manufacturing\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Caixa Completa\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/oem-vs-contract-manufacturing\/\" target=\"_blank\" title=\"OEM vs. fabrico por contrato: Como escolher o modelo certo para o seu projeto\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"409\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/03\/A-Finished-Drawing-Does-Not-Always-Mean-a-Production-Safe-Job.jpg\" class=\"attachment-full size-full wp-image-24371\" alt=\"Um desenho acabado nem sempre significa um trabalho seguro para a produ\u00e7\u00e3o\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/03\/A-Finished-Drawing-Does-Not-Always-Mean-a-Production-Safe-Job.jpg 750w, https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/03\/A-Finished-Drawing-Does-Not-Always-Mean-a-Production-Safe-Job-300x164.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/03\/A-Finished-Drawing-Does-Not-Always-Mean-a-Production-Safe-Job-18x10.jpg 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/oem-vs-contract-manufacturing\/\" target=\"_blank\">\n\t\t\t\tOEM vs. fabrico por contrato: Como escolher o modelo certo para o seu projeto\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n\t\t\t9 de mar\u00e7o de 2026\t\t<\/span>\n\t\t\t\t<span class=\"uael-post__comments\">\n\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-comments\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 192c0-88.4-93.1-160-208-160S0 103.6 0 192c0 34.3 14.1 65.9 38 92-13.4 30.2-35.5 54.2-35.8 54.5-2.2 2.3-2.8 5.7-1.5 8.7S4.8 352 8 352c36.6 0 66.9-12.3 88.7-25 32.2 15.7 70.3 25 111.3 25 114.9 0 208-71.6 208-160zm122 220c23.9-26 38-57.7 38-92 0-66.9-53.5-124.2-129.3-148.1.9 6.6 1.3 13.3 1.3 20.1 0 105.9-107.7 192-240 192-10.8 0-21.3-.8-31.7-1.9C207.8 439.6 281.8 480 368 480c41 0 79.1-9.2 111.3-25 21.8 12.7 52.1 25 88.7 25 3.2 0 6.1-1.9 7.3-4.8 1.3-2.9.7-6.3-1.5-8.7-.3-.3-22.4-24.2-35.8-54.5z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/shengenfab.com\/pt\/oem-vs-contract-manufacturing\/\" target=\"_blank\" aria-labelledby=\"uael-post-24369\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=\"uael-post-24369\">Ler mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   blog\">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/setup-cost-vs-unit-cost-in-sheet-metal-manufacturing\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Caixa Completa\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/setup-cost-vs-unit-cost-in-sheet-metal-manufacturing\/\" target=\"_blank\" title=\"Custo de instala\u00e7\u00e3o vs. custo unit\u00e1rio no fabrico de chapas met\u00e1licas\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/02\/Setup-Cost-vs-Unit-Cost.jpg\" class=\"attachment-full size-full wp-image-24239\" alt=\"Custo de instala\u00e7\u00e3o vs. custo unit\u00e1rio\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/02\/Setup-Cost-vs-Unit-Cost.jpg 750w, https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/02\/Setup-Cost-vs-Unit-Cost-300x200.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2026\/02\/Setup-Cost-vs-Unit-Cost-18x12.jpg 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/shengenfab.com\/pt\/setup-cost-vs-unit-cost-in-sheet-metal-manufacturing\/\" target=\"_blank\">\n\t\t\t\tCusto de instala\u00e7\u00e3o vs. custo unit\u00e1rio no fabrico de chapas met\u00e1licas\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n\t\t\t6 de fevereiro de 2026\t\t<\/span>\n\t\t\t\t<span class=\"uael-post__comments\">\n\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-comments\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 192c0-88.4-93.1-160-208-160S0 103.6 0 192c0 34.3 14.1 65.9 38 92-13.4 30.2-35.5 54.2-35.8 54.5-2.2 2.3-2.8 5.7-1.5 8.7S4.8 352 8 352c36.6 0 66.9-12.3 88.7-25 32.2 15.7 70.3 25 111.3 25 114.9 0 208-71.6 208-160zm122 220c23.9-26 38-57.7 38-92 0-66.9-53.5-124.2-129.3-148.1.9 6.6 1.3 13.3 1.3 20.1 0 105.9-107.7 192-240 192-10.8 0-21.3-.8-31.7-1.9C207.8 439.6 281.8 480 368 480c41 0 79.1-9.2 111.3-25 21.8 12.7 52.1 25 88.7 25 3.2 0 6.1-1.9 7.3-4.8 1.3-2.9.7-6.3-1.5-8.7-.3-.3-22.4-24.2-35.8-54.5z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\tSem coment\u00e1rios\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/shengenfab.com\/pt\/setup-cost-vs-unit-cost-in-sheet-metal-manufacturing\/\" target=\"_blank\" aria-labelledby=\"uael-post-24235\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=\"uael-post-24235\">Ler mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__footer\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Tanto a grava\u00e7\u00e3o a seco como a h\u00famida t\u00eam objectivos distintos no processamento de materiais. A grava\u00e7\u00e3o a seco utiliza plasma ou gravadores em fase de vapor para remover material atrav\u00e9s de reac\u00e7\u00f5es qu\u00edmicas ou bombardeamento f\u00edsico. A grava\u00e7\u00e3o h\u00famida baseia-se em solu\u00e7\u00f5es qu\u00edmicas l\u00edquidas para dissolver materiais alvo atrav\u00e9s de processos de oxida\u00e7\u00e3o e dissolu\u00e7\u00e3o.<\/p>","protected":false},"author":1,"featured_media":15963,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[21],"class_list":["post-15953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-surface-finish"],"_links":{"self":[{"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/posts\/15953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/comments?post=15953"}],"version-history":[{"count":0,"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/posts\/15953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/media\/15963"}],"wp:attachment":[{"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/media?parent=15953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/categories?post=15953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shengenfab.com\/pt\/wp-json\/wp\/v2\/tags?post=15953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}