{"id":13813,"date":"2024-11-26T00:10:24","date_gmt":"2024-11-26T08:10:24","guid":{"rendered":"https:\/\/shengenfab.com\/?page_id=13813"},"modified":"2026-05-08T19:18:58","modified_gmt":"2026-05-09T03:18:58","slug":"industrial-control-box","status":"publish","type":"page","link":"https:\/\/shengenfab.com\/it\/industrial-control-box\/","title":{"rendered":"Scatola di controllo industriale"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13813\" class=\"elementor elementor-13813\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73d45307 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73d45307\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d240608 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d240608\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4800968 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4800968\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-136aa624 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"136aa624\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2eb1df0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2eb1df0e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-245971b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"245971b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28070273 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28070273\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c2ce9d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c2ce9d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b267c15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b267c15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71b215df custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71b215df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62a468f0\" data-id=\"62a468f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6413dced custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6413dced\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7ab6c421\" data-id=\"7ab6c421\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44bd11e8 elementor-widget elementor-widget-image\" data-id=\"44bd11e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"396\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Custom-Industrial-Control-Box.jpg\" class=\"attachment-large size-large wp-image-13826\" alt=\"Custom Industrial Control Box\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Custom-Industrial-Control-Box.jpg 500w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Custom-Industrial-Control-Box-300x238.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Custom-Industrial-Control-Box-15x12.jpg 15w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e06479c\" data-id=\"2e06479c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fae34ee elementor-widget elementor-widget-heading\" data-id=\"4fae34ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Industrial Control Box\/Industrial Control Panel Enclosure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71237d29 elementor-widget elementor-widget-text-editor\" data-id=\"71237d29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Expertly fabricated Industrial Control Box with robust sheet metal construction. Perfect for housing control systems, featuring dust-proof seals, customizable sizes, and durable powder coating. Built to last in harsh environments.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31316e0d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"31316e0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Free quotes within one day<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lead time as fast as 3-5 days<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-dot-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm80 248c0 44.112-35.888 80-80 80s-80-35.888-80-80 35.888-80 80-80 80 35.888 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ISO 9001\uff1a2015 certified<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b203515 elementor-widget elementor-widget-button\" data-id=\"b203515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ace33d3 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ace33d3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-744807c4\" data-id=\"744807c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33f4a183 elementor-widget elementor-widget-heading\" data-id=\"33f4a183\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Custom Industrial Control Box<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa71e44 elementor-widget elementor-widget-text-editor\" data-id=\"2fa71e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Our custom Industrial Control Box features precision sheet metal fabrication with superior protection against environmental hazards. Built with IP-rated enclosures and premium materials, these boxes are engineered to house critical control components, PLCs, and electrical systems.\u00a0Each unit offers flexible configurations, dust-proof sealing, and professional surface finishing.<\/p><p style=\"text-align: left;\">Our control boxes ensure reliable performance and long-term durability, whether for automation, manufacturing, or specialized industrial applications.\u00a0Available in various sizes with options for customized mounting, access panels, and ventilation systems to meet your exact specifications.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-798f3376 elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"798f3376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78b50917 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78b50917\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4289e4cf\" data-id=\"4289e4cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b13fc29 elementor-widget elementor-widget-heading\" data-id=\"6b13fc29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Industrial Control Box Types<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5293ce5e custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5293ce5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-316698ee\" data-id=\"316698ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e223646 elementor-widget elementor-widget-image\" data-id=\"3e223646\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"536\" height=\"536\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-e65324.jpg\" class=\"attachment-large size-large wp-image-13833\" alt=\"Industrial Control Panel Enclosure e65324\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-e65324.jpg 536w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-e65324-300x300.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-e65324-150x150.jpg 150w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-e65324-12x12.jpg 12w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1734536a elementor-widget elementor-widget-heading\" data-id=\"1734536a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Industrial Control Panel Enclosure e65324<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29711267 elementor-widget elementor-widget-text-editor\" data-id=\"29711267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Premium sheet metal enclosure with IP65 protection, featuring robust sealing, customizable dimensions, and professional powder coating for superior industrial equipment protection.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17edbfca elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"17edbfca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2a0107a2\" data-id=\"2a0107a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c5dfc4d elementor-widget elementor-widget-image\" data-id=\"5c5dfc4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-2740.jpg\" class=\"attachment-large size-large wp-image-13832\" alt=\"Industrial Control Panel Enclosure 2740\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-2740.jpg 500w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-2740-300x300.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-2740-150x150.jpg 150w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-2740-12x12.jpg 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff43c72 elementor-widget elementor-widget-heading\" data-id=\"2ff43c72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Industrial Control Panel Enclosure 2740<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72bfd610 elementor-widget elementor-widget-text-editor\" data-id=\"72bfd610\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>NEMA 3 and IP65-rated enclosure, available in steel or aluminum construction, suitable for wall or pad mounting with advanced environmental protection features.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37e6f996 elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"37e6f996\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1307076f\" data-id=\"1307076f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-397c8cb7 elementor-widget elementor-widget-image\" data-id=\"397c8cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-UL.jpg\" class=\"attachment-large size-large wp-image-13838\" alt=\"Industrial Control Panel Enclosure UL\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-UL.jpg 800w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-UL-300x300.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-UL-150x150.jpg 150w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-UL-768x768.jpg 768w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-UL-12x12.jpg 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d50ba5c elementor-widget elementor-widget-heading\" data-id=\"2d50ba5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Industrial Control Panel Enclosure UL<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-263137e elementor-widget elementor-widget-text-editor\" data-id=\"263137e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>UL 508A certified control panel enclosure, engineered for safety compliance, featuring standardized component integration and comprehensive circuit protection.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d8d086d elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"7d8d086d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-74f3ddc\" data-id=\"74f3ddc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52e8be8e elementor-widget elementor-widget-image\" data-id=\"52e8be8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Small-Industrial-Control-Box.jpg\" class=\"attachment-large size-large wp-image-13837\" alt=\"Small Industrial Control Box\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Small-Industrial-Control-Box.jpg 720w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Small-Industrial-Control-Box-300x300.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Small-Industrial-Control-Box-150x150.jpg 150w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Small-Industrial-Control-Box-12x12.jpg 12w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1855323f elementor-widget elementor-widget-heading\" data-id=\"1855323f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Small Industrial Control Box<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75a54e17 elementor-widget elementor-widget-text-editor\" data-id=\"75a54e17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Compact galvanized steel or aluminum enclosure designed for indoor applications, offering efficient space utilization with customizable compartments.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af44b49 elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"7af44b49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ee383a4 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ee383a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4bd84717\" data-id=\"4bd84717\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ed4916d elementor-widget elementor-widget-image\" data-id=\"1ed4916d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"315\" height=\"315\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Roller-Door-Control-Box-1.jpg\" class=\"attachment-large size-large wp-image-13843\" alt=\"Industrial Roller Door Control Box (1)\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Roller-Door-Control-Box-1.jpg 315w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Roller-Door-Control-Box-1-300x300.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Roller-Door-Control-Box-1-150x150.jpg 150w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Roller-Door-Control-Box-1-12x12.jpg 12w\" sizes=\"(max-width: 315px) 100vw, 315px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41c7051d elementor-widget elementor-widget-heading\" data-id=\"41c7051d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Industrial Roller Door Control Box<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe918b elementor-widget elementor-widget-text-editor\" data-id=\"2fe918b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Specialized enclosure for door control systems, featuring weatherproof construction and secure access for tubular motor and VAC control components.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30bc5014 elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"30bc5014\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-30bfae41\" data-id=\"30bfae41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d83dd56 elementor-widget elementor-widget-image\" data-id=\"7d83dd56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"539\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Electrical-Enclosure-Outdoor.jpg\" class=\"attachment-large size-large wp-image-13835\" alt=\"Industrial Electrical Enclosure Outdoor\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Electrical-Enclosure-Outdoor.jpg 539w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Electrical-Enclosure-Outdoor-300x300.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Electrical-Enclosure-Outdoor-150x150.jpg 150w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Electrical-Enclosure-Outdoor-12x12.jpg 12w\" sizes=\"(max-width: 539px) 100vw, 539px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b85a1ae elementor-widget elementor-widget-heading\" data-id=\"6b85a1ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Industrial Electrical Enclosure Outdoor<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e5b8d3a elementor-widget elementor-widget-text-editor\" data-id=\"7e5b8d3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Weather-resistant cabinet with IP55 protection, built to withstand extreme conditions with integrated cooling and advanced sealing systems.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8af77d3 elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"8af77d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-403b413e\" data-id=\"403b413e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d20af84 elementor-widget elementor-widget-image\" data-id=\"2d20af84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Electrical-Enclosure-Cabinet.jpg\" class=\"attachment-large size-large wp-image-13834\" alt=\"Electrical Enclosure Cabinet\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Electrical-Enclosure-Cabinet.jpg 800w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Electrical-Enclosure-Cabinet-300x300.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Electrical-Enclosure-Cabinet-150x150.jpg 150w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Electrical-Enclosure-Cabinet-768x768.jpg 768w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Electrical-Enclosure-Cabinet-12x12.jpg 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc72488 elementor-widget elementor-widget-heading\" data-id=\"4dc72488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Electrical Enclosure Cabinet<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-244780f2 elementor-widget elementor-widget-text-editor\" data-id=\"244780f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wall-mounted cabinet with dual-access doors, designed for indoor electrical installations with organized component layout and secure locking mechanism.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-456e0697 elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"456e0697\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-92ffe97\" data-id=\"92ffe97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e0c0dd7 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e0c0dd7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d9294e9\" data-id=\"6d9294e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1765fb76 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1765fb76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15d7250a\" data-id=\"15d7250a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-182c0d71 elementor-widget elementor-widget-heading\" data-id=\"182c0d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Features of Industrial Control Box<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ab5d4d2 elementor-widget elementor-widget-text-editor\" data-id=\"3ab5d4d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Our industrial control box combines advanced protection and functionality in one robust solution. Expertly crafted with premium-grade sheet metal, these enclosures feature IP-rated protection, dust-proof sealing, and superior ventilation systems. Each box includes essential safety features like grounding systems, circuit protection, and secure cable management.<\/p><p style=\"text-align: left;\">The interior layout accommodates PLCs, HMIs, terminal blocks, and power distribution components with organized wire routing and DIN rail mounting. Built to withstand harsh industrial environments, our control boxes offer flexible mounting options, easy maintenance access, and customizable configurations to protect your critical control equipment and ensure reliable operation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b83897 elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"73b83897\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e86bb97\" data-id=\"e86bb97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15d565e8 elementor-widget elementor-widget-image\" data-id=\"15d565e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-1.jpg\" class=\"attachment-large size-large wp-image-13827\" alt=\"Industrial Control Panel Enclosure\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-1.jpg 500w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-1-300x300.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-1-150x150.jpg 150w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Panel-Enclosure-1-12x12.jpg 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65b67d38 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65b67d38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43d86b7f\" data-id=\"43d86b7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5f61f036 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f61f036\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-53c770c4\" data-id=\"53c770c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48955c63 elementor-widget elementor-widget-image\" data-id=\"48955c63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-Types-1024x768.jpg\" class=\"attachment-large size-large wp-image-13825\" alt=\"Industrial Control Box Types\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-Types-1024x768.jpg 1024w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-Types-300x225.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-Types-768x576.jpg 768w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-Types-1536x1152.jpg 1536w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-Types-16x12.jpg 16w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-Types.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2373878e\" data-id=\"2373878e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7be61f6a elementor-widget elementor-widget-heading\" data-id=\"7be61f6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Applications of Industrial Control Box<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22aa89bf elementor-widget elementor-widget-text-editor\" data-id=\"22aa89bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our industrial control boxes serve diverse applications across multiple industries. In manufacturing, they protect automation systems and assembly line controls. Energy and utilities safeguard power distribution equipment and monitoring systems. These enclosures are essential in wastewater treatment facilities, chemical processing plants, transportation systems, housing critical control components, and electrical systems.<\/p><p>Designed for HVAC applications, oil and gas operations, and food processing facilities, our boxes ensure reliable protection in demanding environments. Each unit features customizable configurations to meet industry requirements, from temperature control to advanced automation systems, delivering optimal performance and safety.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6888495e elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"6888495e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6635ffce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6635ffce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b01e90d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b01e90d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-762062a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"762062a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74f03fe4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74f03fe4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36d812fa custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36d812fa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51a0c0c2\" data-id=\"51a0c0c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-27d5f20c custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27d5f20c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6ccf3f2\" data-id=\"6ccf3f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f583efb elementor-widget elementor-widget-heading\" data-id=\"3f583efb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why Choose Shengen to Customize Your Industrial Control Box<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ed8a9d7 elementor-widget elementor-widget-text-editor\" data-id=\"1ed8a9d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At Shengen, we bring a decade of expertise in crafting precision industrial control boxes. Our experienced engineering team ensures meticulous attention to every detail, from material selection to final finishing. We excel in <a href=\"https:\/\/shengenfab.com\/sheet-metal-prototype\/\" target=\"_blank\" rel=\"noopener\">rapid prototyping<\/a> and efficient mass production, delivering custom solutions that perfectly match your specifications.<\/p><p>With advanced manufacturing facilities, stringent quality control, and competitive pricing, we guarantee superior products that meet international standards. Our responsive customer service and quick turnaround times make your project seamless from design to delivery. Trust Shengen for durable, reliable, and professionally finished control boxes that exceed your expectations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65d70f80 elementor-align-center elementor-widget elementor-widget-global elementor-global-8137 elementor-widget-button\" data-id=\"65d70f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6864b54c\" data-id=\"6864b54c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13bd12c1 elementor-widget elementor-widget-image\" data-id=\"13bd12c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"435\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box.jpg\" class=\"attachment-large size-large wp-image-13824\" alt=\"Industrial Control Box\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box.jpg 580w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-300x225.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2024\/11\/Industrial-Control-Box-16x12.jpg 16w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-140f4a4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"140f4a4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6328a54c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6328a54c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b5827ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b5827ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29e64379 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29e64379\" data-element_type=\"section\" data-e-type=\"section\" id=\"duration\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6da5fa33\" data-id=\"6da5fa33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d662dd2 uael-dual-heading-align-center elementor-widget elementor-widget-uael-dual-color-heading\" data-id=\"6d662dd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"uael-module-content uael-dual-color-heading uael-heading-stack-none\">\n\t\t\t<h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-before-heading\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-first-text\" data-elementor-setting-key=\"before_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">The Process Flow <\/span><\/span><span class=\"uael-adv-heading-stack\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-highlight-text\" data-elementor-setting-key=\"second_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">&amp; <\/span><\/span><span class=\"uael-after-heading\"><span class=\"elementor-inline-editing uael-dual-heading-text uael-third-text\" data-elementor-setting-key=\"after_heading_text\" data-elementor-inline-editing-toolbar=\"basic\">Duration Estimation<\/span><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd91e6b elementor-widget elementor-widget-text-editor\" data-id=\"7fd91e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Please note that the final cost depends on the customized service you require, the specifications of the raw materials used, the relevant national laws, and the distance of transportation. Take the example of booking a tall container of products:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-592f1506 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"592f1506\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65ad6f40\" data-id=\"65ad6f40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3958b321 elementor-widget elementor-widget-heading\" data-id=\"3958b321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Step 1: Drawing Design (within 1 day)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a646b58 elementor-widget elementor-widget-text-editor\" data-id=\"3a646b58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Designers use CAD to quickly as well as accurately modify designs to meet the desired specifications, ensuring that the final product meets the required specifications quickly and accurately.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31668fbe\" data-id=\"31668fbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cbfe1cd elementor-widget elementor-widget-image\" data-id=\"4cbfe1cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"448\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Designers_use_CAD_to_quickly_as_well_as_accurately-1024x574.jpg\" class=\"attachment-large size-large wp-image-3411\" alt=\"\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Designers_use_CAD_to_quickly_as_well_as_accurately-1024x574.jpg 1024w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Designers_use_CAD_to_quickly_as_well_as_accurately-300x168.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Designers_use_CAD_to_quickly_as_well_as_accurately-768x430.jpg 768w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Designers_use_CAD_to_quickly_as_well_as_accurately.jpg 1456w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-663848a4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"663848a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4cce30ab\" data-id=\"4cce30ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54299e3d elementor-widget elementor-widget-heading\" data-id=\"54299e3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Step 2: Product Proofing (1-2 days)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23470ded elementor-widget elementor-widget-text-editor\" data-id=\"23470ded\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Product proofing is an essential part of the manufacturing process that can help businesses ensure the quality and consistency of their products while minimizing risks and costs associated with defects or errors in production.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4071d3be\" data-id=\"4071d3be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a28f759 elementor-widget elementor-widget-image\" data-id=\"2a28f759\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"448\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Product_proofing_is_an_essential_part_of_the_manufactur-1-1024x574.jpg\" class=\"attachment-large size-large wp-image-3412\" alt=\"\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Product_proofing_is_an_essential_part_of_the_manufactur-1-1024x574.jpg 1024w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Product_proofing_is_an_essential_part_of_the_manufactur-1-300x168.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Product_proofing_is_an_essential_part_of_the_manufactur-1-768x430.jpg 768w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Product_proofing_is_an_essential_part_of_the_manufactur-1.jpg 1456w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f084800 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f084800\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5df50512\" data-id=\"5df50512\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98c2ba1 elementor-widget elementor-widget-heading\" data-id=\"98c2ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Step 3: Bulk Manufacturing (1-3 days)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7352e460 elementor-widget elementor-widget-text-editor\" data-id=\"7352e460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Once the specifications and quality of the product are confirmed to be in order, it is ready for mass production.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-174e2054\" data-id=\"174e2054\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fb79c5a elementor-widget elementor-widget-image\" data-id=\"1fb79c5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"448\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._sheet_metal_fabrication_partsfor_mass_production-1-1024x574.jpg\" class=\"attachment-large size-large wp-image-3414\" alt=\"\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._sheet_metal_fabrication_partsfor_mass_production-1-1024x574.jpg 1024w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._sheet_metal_fabrication_partsfor_mass_production-1-300x168.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._sheet_metal_fabrication_partsfor_mass_production-1-768x430.jpg 768w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._sheet_metal_fabrication_partsfor_mass_production-1.jpg 1456w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2765b9a0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2765b9a0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-523425dc\" data-id=\"523425dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-143c09cc elementor-widget elementor-widget-heading\" data-id=\"143c09cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Step 4: Shipping (3-5 days)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ba79d7c elementor-widget elementor-widget-text-editor\" data-id=\"4ba79d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Once the products arrive at their destination, you will receive an alert. You can plan how to collect your shipped goods.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-10849a52\" data-id=\"10849a52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49954153 elementor-widget elementor-widget-image\" data-id=\"49954153\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"448\" src=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Shipping-1-1024x574.jpg\" class=\"attachment-large size-large wp-image-3413\" alt=\"\" srcset=\"https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Shipping-1-1024x574.jpg 1024w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Shipping-1-300x168.jpg 300w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Shipping-1-768x430.jpg 768w, https:\/\/shengenfab.com\/wp-content\/uploads\/2023\/07\/lbc965._Shipping-1.jpg 1456w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a1bc023 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3a1bc023\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc4OCIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Quote Now<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52b7c196 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52b7c196\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fcbefa4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fcbefa4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82f1128 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82f1128\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d9c1194 custom-ele-section-css elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d9c1194\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5735ae0b\" data-id=\"5735ae0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16d271a1 elementor-widget elementor-widget-heading\" data-id=\"16d271a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get A Free Quote<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d5b0a55 elementor-widget elementor-widget-text-editor\" data-id=\"4d5b0a55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contact us to get a free quote and more expertise about sheet metal fabrication. Your project will meet the right solution with Shengen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4067c87c elementor-button-align-stretch elementor-widget elementor-widget-global elementor-global-893 elementor-widget-form\" data-id=\"4067c87c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;\\u4e0b\\u4e00\\u4e2a&quot;,&quot;step_previous_label&quot;:&quot;\\u4e0a\\u4e00\\u4e2a&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:76,&quot;sticky_effects_offset&quot;:75,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"\u65b0\u8868\u5355\" aria-label=\"\u65b0\u8868\u5355\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"13813\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"4067c87c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_59b0978 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_59b0978\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tPhone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_59b0978]\" id=\"form-field-field_59b0978\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Phone\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-upload elementor-field-group elementor-column elementor-field-group-field_3054d6d elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3054d6d\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tUpload files\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input type=\"file\" name=\"form_fields[field_3054d6d]\" id=\"form-field-field_3054d6d\" class=\"elementor-field elementor-size-sm  elementor-upload-field\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_7cab1df elementor-col-100 recaptcha_v3-inline\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_7cab1df\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6Ld96zomAAAAAFa92bnUaWtgdyyax_AThlz6udzh\" data-type=\"v3\" data-action=\"Form\" data-badge=\"inline\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get Instant Quote<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c32ee26\" data-id=\"4c32ee26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60ddb0ef elementor-widget elementor-widget-heading\" data-id=\"60ddb0ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Custom Sheet Metal Fabrication with Easy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a7222e elementor-widget elementor-widget-text-editor\" data-id=\"7a7222e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At Shengen, We turn complex Into Simple! Follow the following three steps to start today!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a264867 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5a264867\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewBox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M416.116778 121.565204 358.155952 66.84561 426.75564 0l220.289268 0L513.315556 121.565204 416.116778 121.565204zM496.194233 568.168615l64.977136-56.24488L617.759438 568.168615 582.410961 963.217398l-66.082967 60.782602L460.883889 963.217398 496.194233 568.168615zM533.563713 144.330081l132.280331-120.001787L628.360168 446.641543l-67.188799 65.320325-54.338274-65.320325L533.563713 144.330081z\" fill=\"#009FE8\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tell us as specific as possible of your needs, provide the drawing, reference picture and share your idea.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewBox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M309.935797 885.784114 177.499744 1004.040223l32.482861-365.364754c0.770649-9.209257 1.502766-18.457047 3.891778-26.125006 2.427545-7.667959 4.932154-13.794619 9.132192-18.457047 0 0 8.554205-7.667959 22.657085-21.501111l41.037066-39.881093 50.747245 53.714245L309.935797 885.784114zM656.650842 901.158564l56.064724 61.420736-66.776747 61.420736L194.569622 1024.000036l138.17739-122.841472L656.650842 901.158564zM690.636469 552.671026c-16.954281 16.877216-30.363576 21.501111-65.659306 21.501111L360.95277 574.172137 305.042175 514.292699l43.695806-44.504987c5.625739-6.126661 12.869841-10.750555 20.268072-13.833152 7.398232-3.044064 13.409295-4.585362 21.077254-4.585362l24.583707 0 265.604224 0 55.872062 59.91797L690.636469 552.671026zM382.877738 122.841472 326.967143 62.923502 392.048462 0l313.191808 0c30.671835 0 45.198572 7.667959 62.26845 27.627771l20.576332 24.583707-78.259419 70.629993L382.877738 122.841472zM725.431277 142.762752l79.762185-70.629993 27.242447 30.710368c3.352324 3.082597 7.089972 10.750555 11.097348 21.501111 1.926623 4.623895 2.35048 9.24779 2.735804 13.833152 0.539454 6.126661-0.038532 16.877216-0.385325 30.710368l-21.578176 227.187364c-2.19635 27.666304-7.359699 38.416859-27.126849 58.338139l-42.578365 39.919625-55.756465-58.338139L725.431277 142.762752z\" fill=\"#009FE8\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">We will work on the best solution according to your requirements and drawing, the specific quote will be provided within 24 hours.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" class=\"icon\" viewBox=\"0 0 1024 1024\" width=\"200\" height=\"200\"><path d=\"M606.286201 901.158566l63.000567 70.629993-32.636991 30.710368c-17.069878 15.297385-36.490237 21.501111-71.785967 21.501111L265.505153 1024.000039 209.594558 964.120601l77.373173-62.962034L606.286201 901.158566zM645.242515 451.330666l58.993191 59.91797L634.491959 574.133606 316.714788 574.133606l-60.804217-62.923502 71.51624-59.91797L645.242515 451.292134zM355.516972 122.841472l-57.413361-59.91797L366.267528 0l302.441253 0c13.833152 0 23.158007 1.502766 26.240603 1.502766 10.904685 1.541298 27.203914 12.291854 40.805872 27.704836l20.576332 24.545175-81.457614 69.088695L355.516972 122.841472zM652.987538 592.55212l69.589617-64.4648 27.011252 27.627772c15.297385 16.877216 20.961656 29.16907 22.464422 46.084818 0.693584 7.667959 1.348636 15.297385 0.462389 23.003877l-22.002033 239.517751c-2.19635 27.627772-8.7854 39.919625-30.093849 59.879438l-35.681055 30.710368-57.952815-66.044631L652.987538 592.55212zM693.215423 139.680156l80.031913-67.547397 20.306605 21.501111c11.983594 13.833152 19.304761 27.666304 20.653397 43.002222 0.539454 6.126661-0.038532 16.877216-1.541298 35.29573l-20.422202 222.602003c-2.04222 29.16907-7.244102 39.919625-24.198383 56.796841l-45.352702 42.963689-57.336296-58.33814L693.215423 139.680156z\" fill=\"#009FE8\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">We will start mass production after getting your approval and deposit, and we will handle the shipment.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Industrial Control Box\/Industrial Control Panel Enclosure Expertly fabricated Industrial Control Box with robust sheet metal construction. Perfect for housing control systems, featuring dust-proof seals, customizable sizes, and durable powder coating. Built to last in harsh environments. Free quotes within one day Lead time as fast as 3-5 days ISO 9001\uff1a2015 certified Get A Quote Custom [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13813","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/shengenfab.com\/it\/wp-json\/wp\/v2\/pages\/13813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shengenfab.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/shengenfab.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/shengenfab.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/shengenfab.com\/it\/wp-json\/wp\/v2\/comments?post=13813"}],"version-history":[{"count":17,"href":"https:\/\/shengenfab.com\/it\/wp-json\/wp\/v2\/pages\/13813\/revisions"}],"predecessor-version":[{"id":13847,"href":"https:\/\/shengenfab.com\/it\/wp-json\/wp\/v2\/pages\/13813\/revisions\/13847"}],"wp:attachment":[{"href":"https:\/\/shengenfab.com\/it\/wp-json\/wp\/v2\/media?parent=13813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}